{"id":2273,"date":"2023-11-24T12:42:48","date_gmt":"2023-11-24T11:42:48","guid":{"rendered":"https:\/\/www.xmesesport.org\/?p=2273"},"modified":"2023-11-24T12:43:49","modified_gmt":"2023-11-24T11:43:49","slug":"el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte","status":"publish","type":"post","link":"https:\/\/www.xmesesport.org\/cat\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/","title":{"rendered":"El CSD lanza una campa\u00f1a para mejorar la salud y el deporte"},"content":{"rendered":"<h3 style=\"text-align: center;\"><span style=\"color: #808080;\"><strong>La iniciativa, presente en prensa, radio, cine, medios digitales y exterior, pretende concienciar sobre la importancia de la pr\u00e1ctica regular de ejercicio f\u00edsico y lograr sociedades m\u00e1s activas. \u201cQueremos dirigirnos directamente al espectador, decirle que no hay excusa que valga, que el \u00fanico obst\u00e1culo para levantarse del sof\u00e1 y hacer deporte es uno mismo\u201d, subraya el presidente del CSD, V\u00edctor Francos<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p>X+MEDIATECA<br \/>\nEl <a href=\"https:\/\/www.csd.gob.es\/es\" target=\"_blank\" rel=\"noopener\">Consejo Superior de Deportes (CSD)<\/a> ha lanzado la campa\u00f1a de publicidad institucional<span style=\"color: #808080;\"><strong> \u2018ACT\u00cdVATE<\/strong><\/span>. La salud se entrena\u2019. Una nueva iniciativa del Gobierno de Espa\u00f1a para combatir el sedentarismo entre la poblaci\u00f3n y concienciar sobre la importancia que la actividad f\u00edsica tiene para la salud. La campa\u00f1a, financiada por la Uni\u00f3n Europea a trav\u00e9s de los <span style=\"color: #808080;\"><strong>Fondos Next Generation<\/strong><\/span>, lanza un mensaje directo a la audiencia, anim\u00e1ndola a dejar atr\u00e1s las habituales excusas -falta de tiempo, de ganas, de constancia, etc.-. As\u00ed, otorga a todas las personas la capacidad de decidir dar el paso definitivo hacia una vida m\u00e1s saludable.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"ACT\u00cdVATE. La salud se entrena\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/6uOppfyx884?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>\u201cMuchas personas consideran el deporte y el ejercicio f\u00edsico como simples actividades de ocio y entretenimiento, olvidando lo necesarios que son para nuestra propia salud f\u00edsica y mental\u201d, se\u00f1ala el presidente del CSD,<span style=\"color: #808080;\"><strong> V\u00edctor Francos<\/strong><\/span>. \u201cCon la campa\u00f1a ACT\u00cdVATE queremos dirigirnos directamente al espectador, decirle que no hay excusa que valga, que el \u00fanico obst\u00e1culo para levantarse del sof\u00e1, hacer deporte y estar m\u00e1s sano es uno mismo\u201d, subraya Francos. La actividad f\u00edsica regular es, en efecto, un factor de gran importancia en la prevenci\u00f3n y tratamiento de enfermedades y patolog\u00edas. Ayuda tambi\u00e9n a mantener una adecuada condici\u00f3n f\u00edsica y al bienestar general, sin olvidar su influencia positiva en la salud mental. El deporte es un eficaz antidepresivo y ansiol\u00edtico, adem\u00e1s de prevenir el deterioro cognitivo.<\/p>\n<p>Seg\u00fan la <span style=\"color: #808080;\"><strong>Organizaci\u00f3n Mundial de la Salud (OMS)<\/strong><\/span>, cada a\u00f1o podr\u00edan evitarse entre cuatro y cinco millones de muertes en el planeta si su poblaci\u00f3n fuese m\u00e1s activa f\u00edsicamente. Sin embargo, casi un tercio de los adultos y m\u00e1s del 80% de los adolescentes no cumplen sus recomendaciones sobre actividad f\u00edsica: entre 150 y 300 minutos de actividad moderada a la semana -o el equivalente en actividad vigorosa- en adultos y 60 minutos al d\u00eda entre menores.<\/p>\n<p>&nbsp;<\/p>\n<p>En Espa\u00f1a, la \u00faltima <span style=\"color: #808080;\"><strong>Encuesta de H\u00e1bitos Deportivos<\/strong> <\/span>refleja que poco m\u00e1s del 50% de la poblaci\u00f3n practica deporte al menos una vez a la semana y s\u00f3lo el <span style=\"color: #808080;\"><strong>23% lo hace cada d\u00eda<\/strong><\/span>. Aunque estos datos han mejorado en los \u00faltimos a\u00f1os, todav\u00eda es necesario concienciar sobre la importancia de llevar a cabo una vida activa y saludable, especialmente entre las personas de m\u00e1s de 65 a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #808080;\"><strong>Informaciones relacionadas<\/strong><\/span><\/h3>\n<blockquote class=\"wp-embedded-content\" data-secret=\"EdS4QFvm7n\"><p><a href=\"https:\/\/www.xmesesport.org\/turismo-deportivo-un-negocio-de-270-millones-de-euros\/\">Turismo deportivo un negocio de 270 millones de euros<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abTurismo deportivo un negocio de 270 millones de euros\u00bb \u2014 Por M&aacute;s Deporte - X+Esport\" src=\"https:\/\/www.xmesesport.org\/turismo-deportivo-un-negocio-de-270-millones-de-euros\/embed\/#?secret=KVV8eNUCgq#?secret=EdS4QFvm7n\" data-secret=\"EdS4QFvm7n\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>La iniciativa, presente medios de comunicaci\u00f3n, pretende concienciar sobre la importancia de la pr\u00e1ctica regular de ejercicio f\u00edsico<\/p>","protected":false},"author":1,"featured_media":2274,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12,43],"tags":[],"class_list":["post-2273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-mediateca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una campa\u00f1a para mejorar la salud y el deporte -X+MEDIATECA<\/title>\n<meta name=\"description\" content=\"La iniciativa, presente medios de comunicaci\u00f3n, pretende concienciar sobre la importancia de la pr\u00e1ctica regular de ejercicio f\u00edsico\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.xmesesport.org\/cat\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una campa\u00f1a para mejorar la salud y el deporte -X+MEDIATECA\" \/>\n<meta property=\"og:description\" content=\"La iniciativa, presente medios de comunicaci\u00f3n, pretende concienciar sobre la importancia de la pr\u00e1ctica regular de ejercicio f\u00edsico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.xmesesport.org\/cat\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/\" \/>\n<meta property=\"og:site_name\" content=\"Por M&aacute;s Deporte - X+Esport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/permesesport\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-24T11:42:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-24T11:43:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.xmesesport.org\/#\/schema\/person\/53e1cceae28ee3da6c7f1ae13f990207\"},\"headline\":\"El CSD lanza una campa\u00f1a para mejorar la salud y el deporte\",\"datePublished\":\"2023-11-24T11:42:48+00:00\",\"dateModified\":\"2023-11-24T11:43:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/\"},\"wordCount\":513,\"publisher\":{\"@id\":\"https:\/\/www.xmesesport.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg\",\"articleSection\":[\"ACTUALIDAD\",\"Mediateca\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/\",\"url\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/\",\"name\":\"Una campa\u00f1a para mejorar la salud y el deporte -X+MEDIATECA\",\"isPartOf\":{\"@id\":\"https:\/\/www.xmesesport.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg\",\"datePublished\":\"2023-11-24T11:42:48+00:00\",\"dateModified\":\"2023-11-24T11:43:49+00:00\",\"description\":\"La iniciativa, presente medios de comunicaci\u00f3n, pretende concienciar sobre la importancia de la pr\u00e1ctica regular de ejercicio f\u00edsico\",\"breadcrumb\":{\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#primaryimage\",\"url\":\"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg\",\"contentUrl\":\"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg\",\"width\":1140,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.xmesesport.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El CSD lanza una campa\u00f1a para mejorar la salud y el deporte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.xmesesport.org\/#website\",\"url\":\"https:\/\/www.xmesesport.org\/\",\"name\":\"Por M&aacute;s Deporte - X+Esport\",\"description\":\"La Comunidad del deporte\",\"publisher\":{\"@id\":\"https:\/\/www.xmesesport.org\/#organization\"},\"alternateName\":\"Per M\u00e9s Esport\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.xmesesport.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.xmesesport.org\/#organization\",\"name\":\"Per M\u00e9s Esport\",\"alternateName\":\"Por M\u00e1s Deporte\",\"url\":\"https:\/\/www.xmesesport.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.xmesesport.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/07\/logo-oficial-scaled.jpg\",\"contentUrl\":\"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/07\/logo-oficial-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Per M\u00e9s Esport\"},\"image\":{\"@id\":\"https:\/\/www.xmesesport.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/permesesport\/\",\"https:\/\/www.linkedin.com\/company\/permesesport\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.xmesesport.org\/#\/schema\/person\/53e1cceae28ee3da6c7f1ae13f990207\",\"name\":\"admin\",\"sameAs\":[\"https:\/\/www.xmesesport.org\"],\"url\":\"https:\/\/www.xmesesport.org\/cat\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una campa\u00f1a para mejorar la salud y el deporte -X+MEDIATECA","description":"La iniciativa, presente medios de comunicaci\u00f3n, pretende concienciar sobre la importancia de la pr\u00e1ctica regular de ejercicio f\u00edsico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.xmesesport.org\/cat\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/","og_locale":"ca_ES","og_type":"article","og_title":"Una campa\u00f1a para mejorar la salud y el deporte -X+MEDIATECA","og_description":"La iniciativa, presente medios de comunicaci\u00f3n, pretende concienciar sobre la importancia de la pr\u00e1ctica regular de ejercicio f\u00edsico","og_url":"https:\/\/www.xmesesport.org\/cat\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/","og_site_name":"Por M&aacute;s Deporte - X+Esport","article_publisher":"https:\/\/www.instagram.com\/permesesport\/","article_published_time":"2023-11-24T11:42:48+00:00","article_modified_time":"2023-11-24T11:43:49+00:00","og_image":[{"width":1140,"height":640,"url":"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#article","isPartOf":{"@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/"},"author":{"name":"admin","@id":"https:\/\/www.xmesesport.org\/#\/schema\/person\/53e1cceae28ee3da6c7f1ae13f990207"},"headline":"El CSD lanza una campa\u00f1a para mejorar la salud y el deporte","datePublished":"2023-11-24T11:42:48+00:00","dateModified":"2023-11-24T11:43:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/"},"wordCount":513,"publisher":{"@id":"https:\/\/www.xmesesport.org\/#organization"},"image":{"@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg","articleSection":["ACTUALIDAD","Mediateca"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/","url":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/","name":"Una campa\u00f1a para mejorar la salud y el deporte -X+MEDIATECA","isPartOf":{"@id":"https:\/\/www.xmesesport.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#primaryimage"},"image":{"@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg","datePublished":"2023-11-24T11:42:48+00:00","dateModified":"2023-11-24T11:43:49+00:00","description":"La iniciativa, presente medios de comunicaci\u00f3n, pretende concienciar sobre la importancia de la pr\u00e1ctica regular de ejercicio f\u00edsico","breadcrumb":{"@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#primaryimage","url":"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg","contentUrl":"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/11\/Imagen-EuropeActiveEU23.jpeg","width":1140,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.xmesesport.org\/el-csd-lanza-una-campana-para-mejorar-la-salud-y-el-deporte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.xmesesport.org\/"},{"@type":"ListItem","position":2,"name":"El CSD lanza una campa\u00f1a para mejorar la salud y el deporte"}]},{"@type":"WebSite","@id":"https:\/\/www.xmesesport.org\/#website","url":"https:\/\/www.xmesesport.org\/","name":"Por M&aacute;s Deporte - X+Esport","description":"La Comunitat de l'Esport","publisher":{"@id":"https:\/\/www.xmesesport.org\/#organization"},"alternateName":"Per M\u00e9s Esport","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.xmesesport.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.xmesesport.org\/#organization","name":"Per M\u00e9s Esport","alternateName":"Por M\u00e1s Deporte","url":"https:\/\/www.xmesesport.org\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.xmesesport.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/07\/logo-oficial-scaled.jpg","contentUrl":"https:\/\/www.xmesesport.org\/wp-content\/uploads\/2023\/07\/logo-oficial-scaled.jpg","width":2560,"height":2560,"caption":"Per M\u00e9s Esport"},"image":{"@id":"https:\/\/www.xmesesport.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/permesesport\/","https:\/\/www.linkedin.com\/company\/permesesport"]},{"@type":"Person","@id":"https:\/\/www.xmesesport.org\/#\/schema\/person\/53e1cceae28ee3da6c7f1ae13f990207","name":"admin","sameAs":["https:\/\/www.xmesesport.org"],"url":"https:\/\/www.xmesesport.org\/cat\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/posts\/2273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/comments?post=2273"}],"version-history":[{"count":2,"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/posts\/2273\/revisions"}],"predecessor-version":[{"id":2277,"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/posts\/2273\/revisions\/2277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/media\/2274"}],"wp:attachment":[{"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/media?parent=2273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/categories?post=2273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.xmesesport.org\/cat\/wp-json\/wp\/v2\/tags?post=2273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}